{"id":57,"date":"2025-05-24T17:49:25","date_gmt":"2025-05-24T17:49:25","guid":{"rendered":"https:\/\/hamrelaydev.wpenginepowered.com\/illinois\/?page_id=57"},"modified":"2025-05-24T18:04:37","modified_gmt":"2025-05-24T18:04:37","slug":"news-archive","status":"publish","type":"page","link":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/","title":{"rendered":"News And Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-57","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News And Events - Illinois CapTel<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News And Events - Illinois CapTel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/\" \/>\n<meta property=\"og:site_name\" content=\"Illinois CapTel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-24T18:04:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/news-archive\\\/\",\"url\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/news-archive\\\/\",\"name\":\"News And Events - Illinois CapTel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/#website\"},\"datePublished\":\"2025-05-24T17:49:25+00:00\",\"dateModified\":\"2025-05-24T18:04:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/news-archive\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/news-archive\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/news-archive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News And Events\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/#website\",\"url\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/\",\"name\":\"Illinois CapTel\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hamiltonrelay.com\\\/illinois\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News And Events - Illinois CapTel","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"News And Events - Illinois CapTel","og_url":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/","og_site_name":"Illinois CapTel","article_modified_time":"2025-05-24T18:04:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/","url":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/","name":"News And Events - Illinois CapTel","isPartOf":{"@id":"https:\/\/hamiltonrelay.com\/illinois\/#website"},"datePublished":"2025-05-24T17:49:25+00:00","dateModified":"2025-05-24T18:04:37+00:00","breadcrumb":{"@id":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hamiltonrelay.com\/illinois\/news-archive\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hamiltonrelay.com\/illinois\/news-archive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hamiltonrelay.com\/illinois\/"},{"@type":"ListItem","position":2,"name":"News And Events"}]},{"@type":"WebSite","@id":"https:\/\/hamiltonrelay.com\/illinois\/#website","url":"https:\/\/hamiltonrelay.com\/illinois\/","name":"Illinois CapTel","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hamiltonrelay.com\/illinois\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/pages\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/pages\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/hamiltonrelay.com\/illinois\/wp-json\/wp\/v2\/media?parent=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}